{"id":1358,"date":"2020-06-09T16:21:30","date_gmt":"2020-06-09T16:21:30","guid":{"rendered":"https:\/\/lease.th-group.eu\/item\/voertuig-c\/"},"modified":"2020-10-28T14:13:41","modified_gmt":"2020-10-28T14:13:41","slug":"fiat-talento","status":"publish","type":"item","link":"https:\/\/lease.th-group.eu\/en\/item\/fiat-talento\/","title":{"rendered":"Fiat talento"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;descriptionrow&#8221; el_id=&#8221;secondary&#8221;][vc_column_text el_class=&#8221;voertuigtitel&#8221;]<\/p>\n<h1>Fiat Talento L2 H1<\/h1>\n<p>[\/vc_column_text][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; el_class=&#8221;grey&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h4><strong>Specificatie<\/strong><\/h4>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;22px&#8221;][vc_column_text]\n<table id=\"tablepress-22\" class=\"tablepress tablepress-id-22\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Motor<\/td><td class=\"column-2\">2 liter - 120 pk<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Wielbasis<\/td><td class=\"column-2\">5399<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Lengte van de laadruimt<\/td><td class=\"column-2\">2937<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Volume<\/td><td class=\"column-2\">6 m\u00b3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-22 from cache -->[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; el_class=&#8221;white&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h4><strong>Uitrusting<\/strong><\/h4>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;22px&#8221;][vc_column_text]\n<table id=\"tablepress-23\" class=\"tablepress tablepress-id-23\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Pro Pack Nav pack<\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Double si\u00e8ge passager<\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Porte coulissante \u00e0 droite<\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Plancher et parois lat\u00e9rales en bois<\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-23 from cache -->[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;picturerow&#8221; css=&#8221;.vc_custom_1591718962292{margin-bottom: -60px !important;}&#8221;][vc_single_image image=&#8221;1097&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_single_image image=&#8221;1106&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_single_image image=&#8221;1103&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_single_image image=&#8221;1189&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;descriptionrow&#8221; el_id=&#8221;secondary&#8221;][vc_column_text el_class=&#8221;voertuigtitel&#8221;] Fiat Talento L2 H1 [\/vc_column_text][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; el_class=&#8221;grey&#8221;][vc_column_inner][vc_column_text] Specificatie [\/vc_column_text][vc_empty_space height=&#8221;22px&#8221;][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221; el_class=&#8221;white&#8221;][vc_column_inner][vc_column_text] Uitrusting [\/vc_column_text][vc_empty_space height=&#8221;22px&#8221;][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;picturerow&#8221; css=&#8221;.vc_custom_1591718962292{margin-bottom: -60px !important;}&#8221;][vc_single_image image=&#8221;1097&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_single_image image=&#8221;1106&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_single_image image=&#8221;1103&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1098,"template":"","categories":[31],"tags":[32],"class_list":["post-1358","item","type-item","status-publish","has-post-thumbnail","hentry","category-fiat-en","tag-van-en"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/item\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/item"}],"about":[{"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/types\/item"}],"author":[{"embeddable":true,"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/item\/1358\/revisions"}],"predecessor-version":[{"id":2038,"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/item\/1358\/revisions\/2038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/media\/1098"}],"wp:attachment":[{"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/categories?post=1358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lease.th-group.eu\/en\/wp-json\/wp\/v2\/tags?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}